{"id":2502,"date":"2020-01-15T10:05:32","date_gmt":"2020-01-15T09:05:32","guid":{"rendered":"https:\/\/www.dasharfenduo.de\/wordpress\/?p=2502"},"modified":"2020-01-15T10:12:41","modified_gmt":"2020-01-15T09:12:41","slug":"solokonzert-fuer-ein-halbes-harfenduo","status":"publish","type":"post","link":"https:\/\/www.dasharfenduo.de\/wordpress\/harfenduo\/unsere-konzerte\/solokonzert-fuer-ein-halbes-harfenduo\/","title":{"rendered":"Solokonzert f\u00fcr ein halbes Harfenduo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Was ist die zweitsch\u00f6nste Art, zu musizieren \u2013 abgesehen vom Spielen im Harfenduo? Nat\u00fcrlich als Solist vor einem Orchester zu sitzen! Laura hat jetzt diese M\u00f6glichkeit: Gemeinsam mit dem Klettenberger Kammerorchester wird sie das Solokonzert f\u00fcr Harfe und Streichorchester von Claude Debussy auff\u00fchren: Die <em>Danses sacr\u00e9e et profane<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das <a rel=\"noreferrer noopener\" aria-label=\"Klettenberger Kammerorchester  (\u00f6ffnet in neuem Tab)\" href=\"http:\/\/s130712640.online.de\/\" target=\"_blank\">Klettenberger Kammerorchester <\/a>ist ein K\u00f6lner Laienorchester. Seit fast 50 Jahren bereichern sie das K\u00f6lner Musikleben. Unter ihrem Dirigenten Hamed Garschi studieren sie anspruchsvolle sinfonische Musik ein: In ihrem Konzert im Januar spielen sie Werke von Claude Debussy, Niels Gade, Edvard Grieg und Franz Schubert. Nicht nur Fans von Harfenmusik sollten so auf ihre Kosten kommen!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong> Wann &amp; Wo:  <br> 25. Januar 2020, Konzertbeginn 17 Uhr, Friedenskirche K\u00f6ln-M\u00fclheim, Wallstra\u00dfe 70<br> 26. Januar 2020, Konzertbeginn 17 Uhr, Tersteegenhaus, Emmastr. 6, K\u00f6ln-S\u00fclz<br><br>Eintritt:<\/strong><br><strong>Karten gibt es ausschlie\u00dflich an der Abendkasse (15 \u20ac\/5 \u20ac erm\u00e4\u00dfigt).<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In unserem Programm von 2018, \u201eRavel vs Debussy\u201c, haben wir die <em>Danses <\/em>von Debussy auch gespielt. Vielleicht erinnert sich der ein oder andere: Da hat Laura den Solopart gespielt, und Daniel den Part des Orchesters auf einer Harfe. Damals haben wir schon einmal auf unserem Blog das Werk vorgestellt. Hier k\u00f6nnt Ihr einen Auszug aus diesem Blogbeitrag lesen:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Claude Debussys <em>Deux Danses<\/em> f\u00fcr Harfe und Streichorchester geh\u00f6ren zu den beliebtesten Werken des Harfenrepertoires. Obwohl Debussy eigentlich f\u00fcr die chromatische Harfe schrieb, ist das St\u00fcck auch auf der heutigen Pedalharfe spielbar.<\/p><p>Die chromatische Harfe mit zwei \u00fcberkreuzten Saitenreihen war einer von vielen Wegen, der Harfe einen m\u00f6glichst gro\u00dfen Tonraum zu erm\u00f6glichen. Heute hat sich die Doppelpedalharfe durchgesetzt &#8211; trotz der komplexen Pedalmechanik ist sie die leichter spielbare Variante der Harfe. <br><br> Hier k\u00f6nnt Ihr eine meiner liebsten Versionen h\u00f6ren, von <a rel=\"noreferrer noopener\" href=\"http:\/\/www.anneleenlenaerts.com\/\" target=\"_blank\">Anneleen Lenaerts<\/a> und dem Orchester brussels philharmonic. Anneleen Lenaerts ist die Soloharfenistin der Wiener Philharmoniker und eine weltweit gefragte Solistin. <br><br> Die wohl originellste Interpretation der T\u00e4nze liefert aber sicherlich <a rel=\"noreferrer noopener\" href=\"http:\/\/www.harplab.net\/\" target=\"_blank\">Park Stickney<\/a>: Er ist der bekannteste Jazz-Harfenist unserer Zeit. Virtuos spielt er nicht nur mit viel mehr Pedalen, als das St\u00fcck ohnehin schon hat, sondern auch mit unseren Erwartungen und H\u00f6rgewohnheiten. Und wann bekommt man als Harfenist schon Szenenapplaus? <br><br>Verschiedener als diese beiden k\u00f6nnen zwei Interpretationen nicht sein &#8211; viel Spa\u00df beim Kennenlernen dieser wundersch\u00f6nen Musik! <\/p><cite>aus unserem Blogbeitrag \u201eLenaerts vs Stickney\u201c vom 4. Mai 2018<\/cite><\/blockquote>\n\n\n<div class=\"column one-second mobile-one\"><div class=\"mcb-column-inner\"><div class=\"responsive-video\"><iframe loading=\"lazy\" width=\"\" height=\"\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/G3UGewCinYw\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/div>Das ist die klassische Version mit Streichorchester.<\/div><\/div>\n\n\n\n<div class=\"column one-second mobile-one\"><div class=\"mcb-column-inner\"><div class=\"responsive-video\"><iframe loading=\"lazy\" width=\"\" height=\"\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/jr9y-lkQNTo\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/div>Und hier ist Park Stickney, der unfassbare Dinge mit einer Harfe macht!<\/div><\/div>\n\n\n\n\n<h3 class=\"wp-block-heading\">Laura &amp; Daniel<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bildquellen:<\/strong><br>Foto von Laura Oetzel von Christian Duxa, Berlin (2019)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was ist die zweitsch\u00f6nste Art, zu musizieren \u2013 abgesehen vom Spielen im Harfenduo? Nat\u00fcrlich als Solist vor einem Orchester zu sitzen! Laura hat jetzt diese M\u00f6glichkeit: Gemeinsam mit dem Klettenberger Kammerorchester wird sie das Solokonzert f\u00fcr Harfe und Streichorchester von Claude Debussy auff\u00fchren: Die Danses sacr\u00e9e et profane. Das Klettenberger<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":2,"featured_media":2507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[59],"tags":[165,169,170,118,167,168,155],"class_list":["post-2502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unsere-konzerte","tag-anneleen-lenaerts","tag-brussels-philharmonics","tag-chromatische-harfe","tag-claude-debussy","tag-danses","tag-jazz","tag-park-stickney"],"_links":{"self":[{"href":"https:\/\/www.dasharfenduo.de\/wordpress\/wp-json\/wp\/v2\/posts\/2502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dasharfenduo.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dasharfenduo.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dasharfenduo.de\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dasharfenduo.de\/wordpress\/wp-json\/wp\/v2\/comments?post=2502"}],"version-history":[{"count":16,"href":"https:\/\/www.dasharfenduo.de\/wordpress\/wp-json\/wp\/v2\/posts\/2502\/revisions"}],"predecessor-version":[{"id":2520,"href":"https:\/\/www.dasharfenduo.de\/wordpress\/wp-json\/wp\/v2\/posts\/2502\/revisions\/2520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dasharfenduo.de\/wordpress\/wp-json\/wp\/v2\/media\/2507"}],"wp:attachment":[{"href":"https:\/\/www.dasharfenduo.de\/wordpress\/wp-json\/wp\/v2\/media?parent=2502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dasharfenduo.de\/wordpress\/wp-json\/wp\/v2\/categories?post=2502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dasharfenduo.de\/wordpress\/wp-json\/wp\/v2\/tags?post=2502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}